{"id":4,"count":3,"description":"","link":"https:\/\/www.erhard-lorenz.de\/deutschland\/category\/bundesstaat\/","name":"Bundesstaat","slug":"bundesstaat","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bundesstaat Archive - Deutschland als Ganzes und der Ewige Bund<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.erhard-lorenz.de\/deutschland\/category\/bundesstaat\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bundesstaat Archive - Deutschland als Ganzes und der Ewige Bund\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.erhard-lorenz.de\/deutschland\/category\/bundesstaat\/\" \/>\n<meta property=\"og:site_name\" content=\"Deutschland als Ganzes und der Ewige Bund\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.erhard-lorenz.de\\\/deutschland\\\/category\\\/bundesstaat\\\/\",\"url\":\"https:\\\/\\\/www.erhard-lorenz.de\\\/deutschland\\\/category\\\/bundesstaat\\\/\",\"name\":\"Bundesstaat Archive - Deutschland als Ganzes und der Ewige Bund\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.erhard-lorenz.de\\\/deutschland\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.erhard-lorenz.de\\\/deutschland\\\/category\\\/bundesstaat\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.erhard-lorenz.de\\\/deutschland\\\/category\\\/bundesstaat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.erhard-lorenz.de\\\/deutschland\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bundesstaat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.erhard-lorenz.de\\\/deutschland\\\/#website\",\"url\":\"https:\\\/\\\/www.erhard-lorenz.de\\\/deutschland\\\/\",\"name\":\"Deutschland als Ganzes oder Nationalstaat Deutschland\",\"description\":\"Deutschland 1871 bis 1918 ab 2008 bis heute\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.erhard-lorenz.de\\\/deutschland\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bundesstaat Archive - Deutschland als Ganzes und der Ewige Bund","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.erhard-lorenz.de\/deutschland\/category\/bundesstaat\/","og_locale":"de_DE","og_type":"article","og_title":"Bundesstaat Archive - Deutschland als Ganzes und der Ewige Bund","og_url":"https:\/\/www.erhard-lorenz.de\/deutschland\/category\/bundesstaat\/","og_site_name":"Deutschland als Ganzes und der Ewige Bund","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.erhard-lorenz.de\/deutschland\/category\/bundesstaat\/","url":"https:\/\/www.erhard-lorenz.de\/deutschland\/category\/bundesstaat\/","name":"Bundesstaat Archive - Deutschland als Ganzes und der Ewige Bund","isPartOf":{"@id":"https:\/\/www.erhard-lorenz.de\/deutschland\/#website"},"breadcrumb":{"@id":"https:\/\/www.erhard-lorenz.de\/deutschland\/category\/bundesstaat\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.erhard-lorenz.de\/deutschland\/category\/bundesstaat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.erhard-lorenz.de\/deutschland\/"},{"@type":"ListItem","position":2,"name":"Bundesstaat"}]},{"@type":"WebSite","@id":"https:\/\/www.erhard-lorenz.de\/deutschland\/#website","url":"https:\/\/www.erhard-lorenz.de\/deutschland\/","name":"Deutschland als Ganzes oder Nationalstaat Deutschland","description":"Deutschland 1871 bis 1918 ab 2008 bis heute","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.erhard-lorenz.de\/deutschland\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.erhard-lorenz.de\/deutschland\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erhard-lorenz.de\/deutschland\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.erhard-lorenz.de\/deutschland\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.erhard-lorenz.de\/deutschland\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}